{"id":7357,"date":"2024-12-27T10:02:59","date_gmt":"2024-12-27T13:02:59","guid":{"rendered":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/?p=7357"},"modified":"2024-12-27T10:03:00","modified_gmt":"2024-12-27T13:03:00","slug":"a-los-exitos-del-gobierno-solo-los-pueden-ver-algunos-incautos","status":"publish","type":"post","link":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/a-los-exitos-del-gobierno-solo-los-pueden-ver-algunos-incautos\/","title":{"rendered":"\u201cA los \u00e9xitos del gobierno s\u00f3lo los pueden ver algunos incautos\u201d"},"content":{"rendered":"\n<p> Por Walter C. Medina<\/p>\n\n\n\n<p>ENTREVISTA A ALEJANDRO OLMOS<\/p>\n\n\n\n<p>El Catedr\u00e1tico e Historiador Alejandro Olmos fue entrevistado por Alex Flores para el programa radial \u201cCenizas de Babilonia. Di\u00e1spora Espa\u00f1ola\u201d. <\/p>\n\n\n\n<p>Olmos, responsable en 2007 de la auditor\u00eda de la deuda externa en el gobierno del ex presidente Rafael Correa; y de a la denuncia de los Tratados de Libre Comercio en Ecuador, entre 2009 y 2017, reflexion\u00f3 sobre las consecuencias de las pol\u00edticas econ\u00f3micas del gobierno de Javier Milei al cumplirse su primer a\u00f1o de mandato. \u201cA los \u00e9xitos del gobierno, s\u00f3lo los pueden ver algunos incautos\u201d.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 opini\u00f3n te merece el presidente Javier Milei?<\/strong><\/p>\n\n\n\n<p>Hablar del actual presidente es extremadamente dif\u00edcil porque tiene un conjunto de aristas muy complicadas. Ayer por la noche dio un discurso mostrando los \u201c\u00e9xitos\u201d de su plan de gobierno, que se traducen \u00fanicamente en la baja de la inflaci\u00f3n. <\/p>\n\n\n\n<p>Ya sabemos c\u00f3mo los economistas manipulan los n\u00fameros, y la baja en la inflaci\u00f3n tiene que ver con que en el mes de diciembre, cuando \u00e9l asumi\u00f3, la inflaci\u00f3n fue del 25 por ciento. Despu\u00e9s baj\u00f3 un poco y despu\u00e9s sigui\u00f3 bajando. Ahora, ese 25 por ciento fue generado por una brutal devaluaci\u00f3n de la moneda del 110 por ciento: no es una inflaci\u00f3n originada en el gobierno anterior, aunque \u00e9l sostiene que s\u00ed.<\/p>\n\n\n\n<p> Adem\u00e1s, el hecho de que \u00e9l asumiera la presidencia ya hab\u00eda determinado que los formadores de precios estuvieran aumentando las cosas con la debida anticipaci\u00f3n para tratar de cubrirse ante cualquier circunstancia que ocurriera. Otra de las cosas de las que tambi\u00e9n hace gala, y tambi\u00e9n lo hizo ayer, es el super\u00e1vit fiscal, que ha llegado en los \u00faltimos once meses a 10 billones de pesos. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"450\" data-id=\"7406\" src=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/704112F8-6D81-44DA-9ABD-F8FDCE6B5F68-1024x450.jpeg\" alt=\"\" class=\"wp-image-7406\" srcset=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/704112F8-6D81-44DA-9ABD-F8FDCE6B5F68-1024x450.jpeg 1024w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/704112F8-6D81-44DA-9ABD-F8FDCE6B5F68-300x132.jpeg 300w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/704112F8-6D81-44DA-9ABD-F8FDCE6B5F68-768x338.jpeg 768w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/704112F8-6D81-44DA-9ABD-F8FDCE6B5F68.jpeg 1242w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Ese super\u00e1vit se logr\u00f3 cortando las transferencias a las provincias en un 76 por ciento, disminuyendo la inversi\u00f3n en obra p\u00fablica en un 70 por ciento, licuando salarios y jubilaciones, y postergando una cantidad de pagos. De todas maneras ese super\u00e1vit de 10 billones de pesos sirvi\u00f3 para pagar m\u00e1s de ocho en intereses de la deuda p\u00fablica; y \u00e9l permanentemente sostuvo que el super\u00e1vit era para pagar la deuda; una deuda de origen francamente espurio, que fue durante a\u00f1os investigada por la Justicia Federal. <\/p>\n\n\n\n<p>Por otra parte hay algunos periodistas que han calculado que el nivel de insultos y descalificaciones a toda aquella persona o instituci\u00f3n que no coincida con el presidente ha llegado al bonito n\u00famero de 4.179. Porque Milei es el \u00fanico presidente en la historia argentina que insulta permanentemente con los peores calificativos; ha utilizado expresiones de vulgaridad sexual incluso en colegios secundarios. <\/p>\n\n\n\n<p>Todo aquel que no coincide con su visi\u00f3n de los hechos es un zurdo de mierda, es comunista, es lo peor de lo peor. Esto en cuento a sus formas operativas, pero hay realidades que no se pueden desconocer: ha ca\u00eddo la inversi\u00f3n p\u00fablica el consumo \u2013que en los \u00faltimos once meses ha llegado la ca\u00edda a m\u00e1s del 15 por ciento-, la pobreza aument\u00f3 entre un 12 y un 14 por ciento en los once meses en que \u00e9l es presidente, la indigencia ha aumentado y en este momento est\u00e1 en un 19 por ciento, y la pobreza en un 52 por ciento, la deuda p\u00fablica ha crecido 92 mil millones de d\u00f3lares; el presidente hizo una curiosa referencia a los que hab\u00edan endeudado a la Argentina, pero daba la casualidad que al lado de \u00e9l estaba su actual Ministro de Econom\u00eda, Luis Caputo, que como Ministro de Econom\u00eda del gobierno de Macri, endeud\u00f3 enormemente a la Argentina y le encaj\u00f3 un pr\u00e9stamo con el FMI, el m\u00e1s grande la de historia del Fondo Monetario Internacional, por 57 mil millones de d\u00f3lares. De modo que esto de \u201clos \u00e9xitos del gobierno\u201d, s\u00f3lo lo pueden ver algunos incautos.  <\/p>\n\n\n\n<p>Lo que me llama la atenci\u00f3n es que las \u00faltimas encuestas dicen que el presidente tiene una intenci\u00f3n favorable del 56 por ciento, casi igual a cuando fue elegido. Nunca he cre\u00eddo demasiado en las encuestas, son muy mentirosas, y en algunos casos pagas por los factores de poder que son los que lo sostienen a Milei. <\/p>\n\n\n\n<p>Entonces esto de que el pueblo argentino en este momento lo apoya como al principio, yo no me lo creo. Yo vivo en Buenos Aires, que es el centro del poder econ\u00f3mico en la Argentina, y uno recorre las calles, ve la gente durmiendo en las calles, ve que en los supermercados cada vez se compra menos, habla con las personas y nadie quiere saber nada con Milei, pero las encuestas parece que dicen lo contrario. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1010\" data-id=\"7408\" src=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/milei-es-hambrejpg-1024x1010-1.webp\" alt=\"\" class=\"wp-image-7408\" srcset=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/milei-es-hambrejpg-1024x1010-1.webp 1024w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/milei-es-hambrejpg-1024x1010-1-300x296.webp 300w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/milei-es-hambrejpg-1024x1010-1-768x758.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Otra de las cosas del presidente es su falta absoluta de respeto por Estado de Derecho. Milei gobierna con Decretos de Necesidad y Urgencia, que es una forma establecida por la Constituci\u00f3n Argentina para situaciones claras de emergencia y supuestamente cuando el Congreso no funciona. <\/p>\n\n\n\n<p>El Congreso ha funcionado estos \u00faltimos once meses, pero la manera de obviar al Congreso es emitir decretos. Es el presidente que m\u00e1s decretos ha emitido desde que existe el periodo constitucional argentino. Son cuarenta y dos decretos de necesidad y urgencia; adem\u00e1s de un mega decreto de necesidad y urgencia, de diciembre el 23, que le permite hacer lo que quiera, sin limitaciones; ese decreto fue rechazado por el Senado de la Naci\u00f3n pero todav\u00eda la C\u00e1mara de Diputados no se anima a tratarlo Basta que una c\u00e1mara no lo anule para que el decreto siga teniendo vigencia. <\/p>\n\n\n\n<p>Hay cosas extremadamente preocupantes; por ejemplo, hay una ley de acceso a la informaci\u00f3n p\u00fablica por la cual cualquier persona, sin necesidad de justificar por qu\u00e9 lo hace, puede pedir a cualquier organismo del Estado que le d\u00e9 informaci\u00f3n sobre decretos, contratos, resoluciones y acuerdos que haga el gobierno. Milei por decreto modific\u00f3 la ley, y ahora hay cosas que no se pueden pedir. <\/p>\n\n\n\n<p>Despues emiti\u00f3 otro decreto, el 846, que es extremadamente peligroso porque la Ley de Administraci\u00f3n Financiera en su Art\u00edculo 65establece que en todo canje de deuda p\u00fablica deben mejorarse los montos, los intereses y las condiciones de contrataci\u00f3n. Milei, a trav\u00e9s del decreto 846, modific\u00f3 el Art\u00edculo 65, y ahora todo canje de deuda ser\u00e1 realizado de acuerdo a las condiciones del mercado. <\/p>\n\n\n\n<p>Y el mercado siempre pone condiciones que no son favorables para los pa\u00edses, sino para ellos mismos y para los inversores. Nos encontramos con un personaje que vino a destruir al Estado, que su posici\u00f3n es la de un topo que desde adentro quiere aniquilarlo. A veces pienso en  las contradicciones del presidente, porque \u00e9l es un gran admirador de los Estados Unidos; y si hay un pa\u00eds que tiene un Estado fuerte, s\u00f3lido, es Estados Unidos. \u201cThe Economist\u201d declar\u00f3 que Milei tiene un soberano desprecio por el Estado.<\/p>\n\n\n\n<p> Este es Javier Milei; y a m\u00ed me llama la atenci\u00f3n c\u00f3mo ha convencido a mucha gente. Por otra parte dijo que ven\u00eda a aniquilar a la casta pol\u00edtica: dirigentes, senadores, diputados; pero gobierna con la casta, porque todo su gabinete est\u00e1 integrado por personas de larga trayectoria pol\u00edtica, muy cuestionados. <\/p>\n\n\n\n<p><strong>\u00bfCrees que a futuro deber\u00eda hacerse una auditor\u00eda de la deuda externa dejada por el gobierno de Macri para determinar qu\u00e9 parte de la deuda es leg\u00edtima y qu\u00e9 parte es ileg\u00edtima?<\/strong><\/p>\n\n\n\n<p>La deuda nosotros la tenemos el 55 por ciento en moneda extranjera, el 45 en moneda local indexada; es decir que es una deuda que se actualiza permanentemente. Pero a esto se suma que como el presidente quiso supuestamente sanear el estado del Banco Central, transfiri\u00f3 deuda del Banco Central al tesoro. Y a los efectos de esa transferencia emiti\u00f3 unas letras que se llaman Lecap, que capitalizan intereses mes a mes. Esas Lecap, dicho por un asesor de Milei, que se fue espantado del lado de Milei, generan una deuda de dos billones de pesos mensuales que se va acumulando permanentemente. <\/p>\n\n\n\n<p>Hablar de auditor\u00eda en Argentina yo dir\u00eda que es una especie de delirio, porque jam\u00e1s ning\u00fan gobierno constitucional quiso auditar la deuda p\u00fablica. Y todos los proyectos que se presentaron para hacerlo ninguno quisieron hacerlo. Adem\u00e1s en este momento tenemos un Congreso que, salvo excepciones, est\u00e1 integrado por mediocres, por trepadores, por gente que le interesa su situaci\u00f3n personal y no el pa\u00eds. <\/p>\n\n\n\n<p>Todo esto determina que el presidente puede seguir haciendo lo que quiere porque nadie se le anima. Es como que hay una especie de miedo subyacente a criticarlo, a cuestionarlo. Para \u00e9l todos los periodistas, sin excepci\u00f3n, son una basura, son ensobrados, reciben plata de otros, Y se ha enfrentado nada m\u00e1s y nada menos que a los dos diarios principales de la Argentina que son La Naci\u00f3n y Clar\u00edn, diciendo que sus periodistas son esbirros de los intereses que quieren perjudicar a la Argentina. Esto te da una pausa de lo que es este presidente.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"420\" height=\"280\" data-id=\"7407\" src=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/javier-milei-con-un-billete-de-cien-dolares-con-OSTQ37P745BJ3AU5BAVINJ2TF4.jpg\" alt=\"\" class=\"wp-image-7407\" srcset=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/javier-milei-con-un-billete-de-cien-dolares-con-OSTQ37P745BJ3AU5BAVINJ2TF4.jpg 420w, https:\/\/xn--tuvozdiasporaespaola-k7b.com\/wp-content\/uploads\/2024\/12\/javier-milei-con-un-billete-de-cien-dolares-con-OSTQ37P745BJ3AU5BAVINJ2TF4-300x200.jpg 300w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><strong> \u00bfC\u00f3mo ves de aqu\u00ed a futuro la posici\u00f3n de Milei respeto al sionismo israelita?<\/strong><\/p>\n\n\n\n<p>El alineamiento de Milei con Israel; \u00e9l es seguidor de una de las ramas m\u00e1s fundamentalistas de la religi\u00f3n jud\u00eda y cada vez que va a los Estados Unidos va a visitar la tumba de ese grupo que es uno de los grupos m\u00e1s ortodoxos del juda\u00edsmo. <\/p>\n\n\n\n<p>Milei, a pesar de ser fundamentalista en un mont\u00f3n de cosas, ejerce el pragmatismo. Hace unos meses cuando venc\u00eda el swap de China, y el gobierno no ten\u00eda dinero para cancelarlo, consigui\u00f3 que China renovara el swap. <\/p>\n\n\n\n<p>Y Milei, que hab\u00eda dicho que nunca se iba a acercar a los chinos, que eran una basura, que eran comunistas, etc, etc, ahora arrug\u00f3; ahora va a sentarse con los comunistas. Primero va a viajar su hermana y seguramente va a viajar \u00e9l, porque ha dicho hace unas semanas que los chinos son buena gente, que mientras uno no los moleste puede hacer negocios. Como a veces se da cuenta que su discurso y que sus pol\u00edticas pueden traerle graves problemas, empieza a girar. Y con China ha sido categ\u00f3rico. <\/p>\n\n\n\n<p>El tema preocupante es la alineaci\u00f3n con Estados Unidos y con Israel. Si la Argentina vota siempre de acuerdo a estos dos pa\u00edses, entonces ya sabemos los que nos espera. El fundamentalismo de Milei va m\u00e1s all\u00e1 de esto, porque hace poco en una reuni\u00f3n en Naciones Unidas sobre los derechos de las mujeres y de los ni\u00f1os el \u00fanico pa\u00eds que vot\u00f3 en contra fue la Argentina, porque hasta Estados Unidos, Israel y Gran Breta\u00f1a votaron a favor. As\u00ed que, ese es Milei.                                                                 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Walter C. Medina ENTREVISTA A ALEJANDRO OLMOS El Catedr\u00e1tico e Historiador Alejandro Olmos fue entrevistado por Alex Flores para el programa radial \u201cCenizas &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u201cA los \u00e9xitos del gobierno s\u00f3lo los pueden ver algunos incautos\u201d\" class=\"read-more button\" href=\"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/a-los-exitos-del-gobierno-solo-los-pueden-ver-algunos-incautos\/#more-7357\" aria-label=\"M\u00e1s en \u201cA los \u00e9xitos del gobierno s\u00f3lo los pueden ver algunos incautos\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":222560522,"featured_media":7409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121852],"tags":[],"class_list":["post-7357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/posts\/7357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/users\/222560522"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/comments?post=7357"}],"version-history":[{"count":2,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/posts\/7357\/revisions"}],"predecessor-version":[{"id":7410,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/posts\/7357\/revisions\/7410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/media\/7409"}],"wp:attachment":[{"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/media?parent=7357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/categories?post=7357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--tuvozdiasporaespaola-k7b.com\/page\/2\/wp-json\/wp\/v2\/tags?post=7357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}